{"id":38,"count":17,"description":"","link":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/","name":"Massachusetts","slug":"massachusetts","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Massachusetts Archives - Rich Green Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massachusetts Archives - Rich Green Photography\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/\" \/>\n<meta property=\"og:site_name\" content=\"Rich Green Photography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/tag\\\/massachusetts\\\/\",\"url\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/tag\\\/massachusetts\\\/\",\"name\":\"Massachusetts Archives - Rich Green Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/tag\\\/massachusetts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/tag\\\/massachusetts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massachusetts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/\",\"name\":\"Rich Green Photography\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/#\\\/schema\\\/person\\\/2c8bfdc92db437e6d6a964f4ef6c3116\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rjgreenphoto.com\\\/Blog\\\/#\\\/schema\\\/person\\\/2c8bfdc92db437e6d6a964f4ef6c3116\",\"name\":\"Rich Green\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g\",\"caption\":\"Rich Green\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.rjgreenphoto.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massachusetts Archives - Rich Green Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/","og_locale":"en_US","og_type":"article","og_title":"Massachusetts Archives - Rich Green Photography","og_url":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/","og_site_name":"Rich Green Photography","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/","url":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/","name":"Massachusetts Archives - Rich Green Photography","isPartOf":{"@id":"https:\/\/rjgreenphoto.com\/Blog\/#website"},"breadcrumb":{"@id":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/rjgreenphoto.com\/Blog\/tag\/massachusetts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rjgreenphoto.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Massachusetts"}]},{"@type":"WebSite","@id":"https:\/\/rjgreenphoto.com\/Blog\/#website","url":"https:\/\/rjgreenphoto.com\/Blog\/","name":"Rich Green Photography","description":"","publisher":{"@id":"https:\/\/rjgreenphoto.com\/Blog\/#\/schema\/person\/2c8bfdc92db437e6d6a964f4ef6c3116"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rjgreenphoto.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/rjgreenphoto.com\/Blog\/#\/schema\/person\/2c8bfdc92db437e6d6a964f4ef6c3116","name":"Rich Green","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g","caption":"Rich Green"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/f86d2815e7218d79dc2fbc73c1a3de4527813ed92afd31fe99d7461036755941?s=96&r=g"},"sameAs":["http:\/\/www.rjgreenphoto.com"]}]}},"_links":{"self":[{"href":"https:\/\/rjgreenphoto.com\/Blog\/wp-json\/wp\/v2\/tags\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rjgreenphoto.com\/Blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rjgreenphoto.com\/Blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rjgreenphoto.com\/Blog\/wp-json\/wp\/v2\/posts?tags=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}